{"id":58405,"date":"2017-11-20T09:42:49","date_gmt":"2017-11-20T08:42:49","guid":{"rendered":"http:\/\/local.cg2021.it\/marchio\/flo-clo\/"},"modified":"2017-11-20T09:42:49","modified_gmt":"2017-11-20T08:42:49","slug":"flo-clo","status":"publish","type":"marchio","link":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/","title":{"rendered":"FLO &amp; CLO"},"featured_media":58406,"template":"","class_list":["post-58405","marchio","type-marchio","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FLO &amp; CLO - Centergross<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FLO &amp; CLO - Centergross\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/\" \/>\n<meta property=\"og:site_name\" content=\"Centergross\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.centergross.com\/wp-content\/uploads\/2021\/09\/d12839ce4bfac9cb1d92c5267ed6a70d69747755brand138-2013-06-24-14-23-32.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/\",\"url\":\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/\",\"name\":\"FLO &amp; CLO - Centergross\",\"isPartOf\":{\"@id\":\"https:\/\/www.centergross.com\/en\/#website\"},\"datePublished\":\"2017-11-20T08:42:49+00:00\",\"dateModified\":\"2017-11-20T08:42:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.centergross.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marchi\",\"item\":\"https:\/\/www.centergross.com\/en\/marchio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FLO &amp; CLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.centergross.com\/en\/#website\",\"url\":\"https:\/\/www.centergross.com\/en\/\",\"name\":\"Centergross\",\"description\":\"We work for your business\",\"publisher\":{\"@id\":\"https:\/\/www.centergross.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.centergross.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.centergross.com\/en\/#organization\",\"name\":\"Centergross srl\",\"url\":\"https:\/\/www.centergross.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.centergross.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.centergross.com\/wp-content\/uploads\/2021\/09\/logo-social-quad3.png\",\"contentUrl\":\"https:\/\/www.centergross.com\/wp-content\/uploads\/2021\/09\/logo-social-quad3.png\",\"width\":800,\"height\":800,\"caption\":\"Centergross srl\"},\"image\":{\"@id\":\"https:\/\/www.centergross.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FLO &amp; CLO - Centergross","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/","og_locale":"en_US","og_type":"article","og_title":"FLO &amp; CLO - Centergross","og_url":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/","og_site_name":"Centergross","og_image":[{"width":768,"height":768,"url":"https:\/\/www.centergross.com\/wp-content\/uploads\/2021\/09\/d12839ce4bfac9cb1d92c5267ed6a70d69747755brand138-2013-06-24-14-23-32.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/","url":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/","name":"FLO &amp; CLO - Centergross","isPartOf":{"@id":"https:\/\/www.centergross.com\/en\/#website"},"datePublished":"2017-11-20T08:42:49+00:00","dateModified":"2017-11-20T08:42:49+00:00","breadcrumb":{"@id":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.centergross.com\/en\/marchio\/flo-clo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.centergross.com\/en\/"},{"@type":"ListItem","position":2,"name":"Marchi","item":"https:\/\/www.centergross.com\/en\/marchio\/"},{"@type":"ListItem","position":3,"name":"FLO &amp; CLO"}]},{"@type":"WebSite","@id":"https:\/\/www.centergross.com\/en\/#website","url":"https:\/\/www.centergross.com\/en\/","name":"Centergross","description":"We work for your business","publisher":{"@id":"https:\/\/www.centergross.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.centergross.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.centergross.com\/en\/#organization","name":"Centergross srl","url":"https:\/\/www.centergross.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.centergross.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.centergross.com\/wp-content\/uploads\/2021\/09\/logo-social-quad3.png","contentUrl":"https:\/\/www.centergross.com\/wp-content\/uploads\/2021\/09\/logo-social-quad3.png","width":800,"height":800,"caption":"Centergross srl"},"image":{"@id":"https:\/\/www.centergross.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.centergross.com\/en\/wp-json\/wp\/v2\/marchio\/58405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centergross.com\/en\/wp-json\/wp\/v2\/marchio"}],"about":[{"href":"https:\/\/www.centergross.com\/en\/wp-json\/wp\/v2\/types\/marchio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.centergross.com\/en\/wp-json\/wp\/v2\/media\/58406"}],"wp:attachment":[{"href":"https:\/\/www.centergross.com\/en\/wp-json\/wp\/v2\/media?parent=58405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}